{"id":444,"date":"2022-10-20T22:22:59","date_gmt":"2022-10-20T13:22:59","guid":{"rendered":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/?page_id=444"},"modified":"2026-08-07T15:53:26","modified_gmt":"2026-08-07T06:53:26","slug":"event-jh","status":"publish","type":"page","link":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/","title":{"rendered":"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09"},"content":{"rendered":"\n<div class=\"wp-block-cover is-light\" style=\"min-height:142px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-white-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#2d7fbe\">\u826f\u304d\u601d\u3044\u51fa\u3068\u6210\u9577\u306e\u7ce7\u306b\u306a\u308b<br>\u884c\u4e8b\u3084\u30c1\u30e3\u30f3\u30b9\u3082\u591a\u5f69\u306b\u7528\u610f\u3002<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u751f\u5f92\u305f\u3061\u306f\u5e74\u9593\u3092\u901a\u3057\u3066\u69d8\u3005\u306a\u884c\u4e8b\u306b\u53d6\u308a\u7d44\u307f\u307e\u3059\u3002\u6bd4\u53e1\u306e\u5cf0\u3005\u3092\u6b69\u304d\u3001\u8af8\u5802\u3092\u53c2\u62dd\u3059\u308b\u4e09\u5854\u5de1\u62dd\u306f\u3001\u672c\u6821\u306b\u306f\u6b20\u304b\u305b\u306a\u3044\u5927\u5207\u306a\u884c\u4e8b\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<br>\u305d\u306e\u4ed6\u3001\u5bbf\u6cca\u3092\u4f34\u3046\u4f53\u9a13\u5408\u5bbf\u306a\u3069\u3001\u8272\u3005\u306a\u884c\u4e8b\u306e\u4e2d\u3067\u306e\u767a\u898b\u3084\u611f\u52d5\u304c\u3001\u5fc3\u3092\u5927\u304d\u304f\u523a\u6fc0\u3057\u307e\u3059\u3002<br>\u591a\u304f\u306e\u884c\u4e8b\u3092\u7d4c\u9a13\u3059\u308b\u3053\u3068\u3067\u3001\u4ef2\u9593\u3068\u306e\u5354\u8abf\u6027\u3084\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u306e\u529b\u3092\u80b2\u3093\u3067\u3044\u304d\u307e\u3059\u3002<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><th>4\u6708<br>April<\/th><th>5\u6708<br>May<\/th><th>6\u6708<br>June<\/th><\/tr><tr><td>\u5165\u5b66\u5f0f<br>\u59cb\u696d\u5f0f<br>\u8ab2\u984c\u78ba\u8a8d\u30c6\u30b9\u30c8\uff082\u5e74\uff09<br>\u30b9\u30c6\u30c3\u30d7\u30c6\u30b9\u30c8\uff083\u5e74\uff09<br>\u9632\u72af\u6559\u80b2<\/td><td>\u4f53\u80b2\u5927\u4f1a<br>\u6388\u696d\u53c2\u89b3<br>\u9032\u8def\u8aac\u660e\u4f1a\uff083\u5e74\uff09<br>\u6625\u5b63\u7dcf\u4f53\u3001\u5439\u594f\u697d\u796d<br>\u82f1\u8a9e\u691c\u5b9a\u203b<br>\u4e2d\u9593\u8a66\u9a13<\/td><td>\u5b66\u5712\u611f\u8b1d\u306e\u65e5<br>\u89aa\u5e2b\u4f1a\u7dcf\u4f1a<br>\u30b9\u30c6\u30c3\u30d7\u30c6\u30b9\u30c8\uff083\u5e74\uff09<br>\u5b66\u529b\u5411\u4e0a\u9031\u9593\u3000<br>\u6821\u5916\u5b66\u7fd2<br>\u300c\u751f\u547d\u306e\u5b89\u5168\u6559\u80b2\u300d1\u30013\u5e74\u751f\u5bfe\u8c61<br>\u671f\u672b\u8a66\u9a13<br>\u590f\u306e\u6388\u696d\u7814\u7a76\u4f1a<\/td><\/tr><tr><th>7\u6708<br>July<\/th><th>8\u6708<br>August<\/th><th>9\u6708<br>September<\/th><\/tr><tr><td>\u6821\u5185\u4eba\u6a29\u30c7\u30fc<br>\u61c7\u8ac7\u4f1a<br>\u7d42\u696d\u5f0f<br>\u590f\u5b63\u7dcf\u4f53<br>\u5439\u594f\u697d\u30b3\u30f3\u30af\u30fc\u30eb<br>\u8aad\u66f8\u9031\u9593<\/td><td>\u5e0c\u671b\u8005\u5b66\u7fd2\u4f1a<br>\u6f22\u5b57\u691c\u5b9a\u203b<br>\u6570\u5b66\u691c\u5b9a\u203b<\/td><td>\u59cb\u696d\u5f0f<br>\u30b7\u30a7\u30a4\u30af\u30a2\u30a6\u30c8\u8a13\u7df4<br>\u8ab2\u984c\u78ba\u8a8d\u30c6\u30b9\u30c8\uff081\u30fb2\u5e74\uff09<br>\u30b9\u30c6\u30c3\u30d7\u30c6\u30b9\u30c8\uff083\u5e74\uff09<br>\u6587\u5316\u796d<br>\u82b8\u8853\u9451\u8cde<\/td><\/tr><tr><th>10\u6708<br>October<\/th><th>11\u6708<br>November<\/th><th>12\u6708<br>December<\/th><\/tr><tr><td>\u5b66\u529b\u5411\u4e0a\u9031\u9593<br>\u82f1\u8a9e\u691c\u5b9a\u203b<br>\u30b9\u30c6\u30c3\u30d7\u30c6\u30b9\u30c8\uff083\u5e74\uff09<br>\u79cb\u5b63\u7dcf\u4f53<br>\u5275\u7acb\u8a18\u5ff5\u65e5<br>\u4e2d\u9593\u8a66\u9a13<br>\u4e2d\u9ad8\u5408\u540c\u9632\u707d\u8a13\u7df4<br>\u6821\u5916\u5b66\u7fd2<br>\u300c\u751f\u547d\u306e\u5b89\u5168\u6559\u80b2\u300d2\u5e74\u751f\u5bfe\u8c61<\/td><td>\u4e09\u8005\u61c7\u8ac7\u4f1a\uff083\u5e74\uff09<br>\u751f\u5f92\u4f1a\u6539\u9078\u9078\u6319<br>\u9032\u8def\u8aac\u660e\u4f1a\uff082\u5e74\uff09<br>\u5b66\u529b\u5411\u4e0a\u9031\u9593<br>\u8aad\u66f8\u9031\u9593<br>\u6f22\u5b57\u691c\u5b9a\u203b\u3000<br>\u300c\u751f\u547d\u306e\u5b89\u5168\u6559\u80b2\u300d2\u5e74\u751f\u5bfe\u8c61<br>\u671f\u672b\u8a66\u9a13<br>\u79cb\u306e\u6388\u696d\u7814\u7a76\u4f1a<\/td><td>\u6821\u5185\u4eba\u6a29\u30c7\u30fc<br>\u5b66\u7fd2\u78ba\u8a8d\u30c6\u30b9\u30c8<br>\u61c7\u8ac7\u4f1a<br>\u7d42\u696d\u5f0f<br>\u89aa\u5e2b\u4f1a\u7814\u7a76\u4f1a<\/td><\/tr><tr><th>1\u6708<br>January<\/th><th>2\u6708<br>February<\/th><th>3\u6708<br>March<\/th><\/tr><tr><td>\u59cb\u696d\u5f0f<br>\u8ab2\u984c\u78ba\u8a8d\u30c6\u30b9\u30c8\uff081\u5e74\uff09<br>\u30b9\u30c6\u30c3\u30d7\u30c6\u30b9\u30c8\uff082\u30fb3\u5e74\uff09<br>\u82f1\u8a9e\u691c\u5b9a\u203b<br>\u8aad\u66f8\u9031\u9593<\/td><td>\u6bd4\u53e1\u5c71\u9ad8\u6821\u5165\u8a66<br>\u5352\u696d\u8a66\u9a13\uff083\u5e74\uff09<br>\u5b66\u5e74\u672b\u8a66\u9a13\uff081\u30fb2\u5e74\uff09<br>\u5bbf\u6cca\u5408\u5bbf\uff081\u5e74\uff09<br>\u5bbf\u6cca\u7814\u4fee\uff082\u5e74\uff09<\/td><td>\u6570\u5b66\u691c\u5b9a\u203b<br>\u5352\u696d\u5f0f<br>\u61c7\u8ac7\u4f1a\uff081\u30fb2\u5e74\uff09<br>\u4fee\u4e86\u5f0f<br>\u6d77\u5916\u7814\u4fee<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u3010\u6ce8\u3011\u5b9f\u60c5\u306b\u5408\u308f\u305b\u3066\u5e74\u9593\u884c\u4e8b\u3092\u5909\u66f4\u3059\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002<br>\u307e\u305f\u5e74\u5ea6\u306b\u3088\u3063\u3066\u5b9f\u65bd\u6708\u304c\u304b\u308f\u308b\u5834\u5408\u3082\u3042\u308a\u307e\u3059\u3002<br>\u203b\uff1d\u5404\u691c\u5b9a\u8a66\u9a13\u306f\u672c\u6821\u3092\u4f1a\u5834\u3068\u3057\u3066\u5e0c\u671b\u8005\u3092\u5bfe\u8c61\u306b\u5b9f\u65bd\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"\u751f\u5f92\u305f\u3061\u306f\u5e74\u9593\u3092\u901a\u3057\u3066\u69d8\u3005\u306a\u884c\u4e8b\u306b\u53d6\u308a\u7d44\u307f\u307e\u3059\u3002\u6bd4\u53e1\u306e\u5cf0\u3005\u3092\u6b69\u304d\u3001\u8af8\u5802\u3092\u53c2\u62dd\u3059\u308b\u4e09\u5854\u5de1\u62dd\u306f\u3001\u672c\u6821\u306b\u306f\u6b20\u304b\u305b\u306a\u3044\u5927\u5207\u306a\u884c\u4e8b\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002","protected":false},"author":1,"featured_media":5332,"parent":65,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-444","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821\" \/>\n<meta property=\"og:description\" content=\"\u751f\u5f92\u305f\u3061\u306f\u5e74\u9593\u3092\u901a\u3057\u3066\u69d8\u3005\u306a\u884c\u4e8b\u306b\u53d6\u308a\u7d44\u307f\u307e\u3059\u3002\u6bd4\u53e1\u306e\u5cf0\u3005\u3092\u6b69\u304d\u3001\u8af8\u5802\u3092\u53c2\u62dd\u3059\u308b\u4e09\u5854\u5de1\u62dd\u306f\u3001\u672c\u6821\u306b\u306f\u6b20\u304b\u305b\u306a\u3044\u5927\u5207\u306a\u884c\u4e8b\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-07T06:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-content\/uploads\/2025\/09\/img-2025-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/\",\"url\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/\",\"name\":\"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/img-2025-02.jpg\",\"datePublished\":\"2022-10-20T13:22:59+00:00\",\"dateModified\":\"2026-08-07T06:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/img-2025-02.jpg\",\"contentUrl\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/img-2025-02.jpg\",\"width\":1100,\"height\":619},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/event-jh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4e2d\u5b66\u6821\",\"item\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/junior_high_school\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/#website\",\"url\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/\",\"name\":\"\u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hieizan.ed.jp\\\/hieizan-jh-hs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/","og_locale":"ja_JP","og_type":"article","og_title":"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821","og_description":"\u751f\u5f92\u305f\u3061\u306f\u5e74\u9593\u3092\u901a\u3057\u3066\u69d8\u3005\u306a\u884c\u4e8b\u306b\u53d6\u308a\u7d44\u307f\u307e\u3059\u3002\u6bd4\u53e1\u306e\u5cf0\u3005\u3092\u6b69\u304d\u3001\u8af8\u5802\u3092\u53c2\u62dd\u3059\u308b\u4e09\u5854\u5de1\u62dd\u306f\u3001\u672c\u6821\u306b\u306f\u6b20\u304b\u305b\u306a\u3044\u5927\u5207\u306a\u884c\u4e8b\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002","og_url":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/","og_site_name":"\u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821","article_modified_time":"2026-08-07T06:53:26+00:00","og_image":[{"width":1100,"height":619,"url":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-content\/uploads\/2025\/09\/img-2025-02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"3\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/","url":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/","name":"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09 | \u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821","isPartOf":{"@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/#primaryimage"},"image":{"@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/#primaryimage"},"thumbnailUrl":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-content\/uploads\/2025\/09\/img-2025-02.jpg","datePublished":"2022-10-20T13:22:59+00:00","dateModified":"2026-08-07T06:53:26+00:00","breadcrumb":{"@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/#primaryimage","url":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-content\/uploads\/2025\/09\/img-2025-02.jpg","contentUrl":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-content\/uploads\/2025\/09\/img-2025-02.jpg","width":1100,"height":619},{"@type":"BreadcrumbList","@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/event-jh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/"},{"@type":"ListItem","position":2,"name":"\u4e2d\u5b66\u6821","item":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/junior_high_school\/"},{"@type":"ListItem","position":3,"name":"\u5e74\u9593\u884c\u4e8b\uff08\u4e2d\u5b66\u6821\uff09"}]},{"@type":"WebSite","@id":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/#website","url":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/","name":"\u6bd4\u53e1\u5c71\u4e2d\u5b66\u6821\u30fb\u9ad8\u7b49\u5b66\u6821","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/pages\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":13,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/pages\/444\/revisions"}],"predecessor-version":[{"id":6461,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/pages\/444\/revisions\/6461"}],"up":[{"embeddable":true,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/pages\/65"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/media\/5332"}],"wp:attachment":[{"href":"https:\/\/hieizan.ed.jp\/hieizan-jh-hs\/wp-json\/wp\/v2\/media?parent=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}